{"id":5279,"date":"2020-05-15T14:31:59","date_gmt":"2020-05-15T12:31:59","guid":{"rendered":"https:\/\/hamburg-daressalaam.de\/covid-19-in-tanzania\/"},"modified":"2022-05-09T22:11:39","modified_gmt":"2022-05-09T20:11:39","slug":"covid-19-in-tanzania","status":"publish","type":"page","link":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/","title":{"rendered":"COVID-19 in Tanzania"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:25px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-1\"><h1 style=\"text-align: center;\">CORONA AID<br \/>\nfor our partner city Dar es Salaam<\/h1>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:40px;width:100%;max-width:50px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#e53540;border-color:#e53540;border-top-width:4px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:180px;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"563\" title=\"web_COVID_AUFRUF4\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all\" alt class=\"img-responsive wp-image-4866\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4-200x188.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4-400x375.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&amp;w=60 60w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&amp;w=120 120w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&amp;w=300 300w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&amp;w=480 480w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&amp;w=540 540w\" sizes=\"(max-width: 1024px) 100vw, 600px\" \/><\/span><\/div><\/div><div class=\"fusion-text fusion-text-2\"><p><strong><img decoding=\"async\" class=\"wp-image-2252 aligncenter\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png?strip=all&resize=261%2C276\" alt=\"\" width=\"261\" height=\"276\"><\/strong><\/p>\n<p><strong>Dear friends of global health,<\/strong><\/p>\n<p>we receive urgent requests for support from our partner city Dar es Salaam. Corona has now arrived there and the people are afraid because Dar es Salaam is the hotspot of Tanzania. Many there do not have the means to purchase additional needed items, such as disinfectants and protective clothing. Poor people in particular are in need.<\/p>\n<p><strong>What is it about at the moment?<\/strong><\/p>\n<\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:13px;--awb-content-font-size:16px;--awb-icon-alignment:left;--awb-hover-color:#f9f9f9;--awb-border-color:#cccccc;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#ffffff;--awb-title-color:#e53540;--awb-content-color:#000000;--awb-icon-box-color:#e53540;--awb-toggle-hover-accent-color:#00a4c4;--awb-title-font-family:&quot;Lexend Exa&quot;;--awb-title-font-weight:regular;--awb-title-font-style:normal;--awb-title-font-size:16px;--awb-title-letter-spacing:0px;--awb-title-line-height:1.5;--awb-content-font-family:&quot;Montserrat&quot;;--awb-content-font-style:normal;--awb-content-font-weight:regular;\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-5279-1\"><div class=\"fusion-panel panel-default panel-1a5062b47bea0d9a1 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_1a5062b47bea0d9a1\"><a aria-expanded=\"false\" aria-controls=\"1a5062b47bea0d9a1\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5279-1\" data-target=\"#1a5062b47bea0d9a1\" href=\"#1a5062b47bea0d9a1\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Stop transmissions in poor neighborhoods - educate and inform people.<\/span><\/a><\/h4><\/div><div id=\"1a5062b47bea0d9a1\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_1a5062b47bea0d9a1\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><img decoding=\"async\" class=\" wp-image-2202 aligncenter\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01.png?strip=all\" alt=\"\" width=\"404\" height=\"404\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01-66x66.png?strip=all 66w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01-150x150.png?strip=all 150w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01-200x200.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01-300x300.png?strip=all 300w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01-400x400.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_01.png?strip=all 446w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/>In Dar es Salaam, a curfew cannot be implemented because over 70% of the population works in the informal sector and relies on daily earnings to provide food for their families. Due to the cramped living conditions, keeping a distance is not possible. Markets and public transport are particularly crowded. (Both offer the most acquisition opportunities)<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-01edbd6dcc9d0aa9e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_01edbd6dcc9d0aa9e\"><a aria-expanded=\"false\" aria-controls=\"01edbd6dcc9d0aa9e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5279-1\" data-target=\"#01edbd6dcc9d0aa9e\" href=\"#01edbd6dcc9d0aa9e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Volunteers inform the local population - they need protective clothing<\/span><\/a><\/h4><\/div><div id=\"01edbd6dcc9d0aa9e\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_01edbd6dcc9d0aa9e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><img decoding=\"async\" class=\"wp-image-2205 aligncenter\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all\" alt=\"\" width=\"853\" height=\"430\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-200x101.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-300x151.png?strip=all 300w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-400x202.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-540x272.png?strip=all 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-600x303.png?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-768x387.png?strip=all 768w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-800x404.png?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-1024x517.png?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-1200x605.png?strip=all 1200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02-1536x775.png?strip=all 1536w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all 1570w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all&amp;w=471 471w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all&amp;w=942 942w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all&amp;w=1099 1099w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all&amp;w=1256 1256w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_02.png?strip=all&amp;w=1413 1413w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/><\/p>\n<p>Regular hand washing and masks, as well as good information, are now the key measures to limit the spread of the virus in these neighborhoods. Three partners have approached us for support.<\/p>\n<p>The Kigamboni Community Center and the umbrella organization of Tanzanian youth organizations plan to go door-to-door with volunteers to provide information in poor neighborhoods. The Ladies Joint Forum aims to educate the people of Vingunguti, targeting women in particular. For this, the volunteers need protective clothing.<\/p>\n<p>So that it doesn&#8217;t stop them from educating, there need to be hand-washing stations &#8211; there is hardly any running water for washing hands &#8211; and masks that are affordable for people in these neighborhoods.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-97d632d7b670ca21e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_97d632d7b670ca21e\"><a aria-expanded=\"false\" aria-controls=\"97d632d7b670ca21e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5279-1\" data-target=\"#97d632d7b670ca21e\" href=\"#97d632d7b670ca21e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Strengthen self-initiative<\/span><\/a><\/h4><\/div><div id=\"97d632d7b670ca21e\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_97d632d7b670ca21e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Other groups are to make water tanks for hand washing. On the one hand, this stimulates the local economy and gives people an income. These are produced locally and therefore a bit cheaper. A subsidy through donations would make it possible to offer the masks at an affordable price in these neighborhoods. It is precisely for this co-financing that we need donations.<img decoding=\"async\" class=\" wp-image-2207 aligncenter\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03.png?strip=all\" alt=\"\" width=\"512\" height=\"512\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-66x66.png?strip=all 66w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-150x150.png?strip=all 150w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-200x200.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-300x300.png?strip=all 300w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-400x400.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03-600x600.png?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03.png?strip=all 607w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03.png?strip=all&amp;w=485 485w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_03.png?strip=all&amp;w=546 546w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-76b0bb85ce6fbce07 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_76b0bb85ce6fbce07\"><a aria-expanded=\"false\" aria-controls=\"76b0bb85ce6fbce07\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5279-1\" data-target=\"#76b0bb85ce6fbce07\" href=\"#76b0bb85ce6fbce07\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Secure health care<\/span><\/a><\/h4><\/div><div id=\"76b0bb85ce6fbce07\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_76b0bb85ce6fbce07\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><img decoding=\"async\" class=\" wp-image-2208 aligncenter\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all\" alt=\"\" width=\"846\" height=\"439\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-200x104.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-300x156.png?strip=all 300w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-400x208.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-600x311.png?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-768x398.png?strip=all 768w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-800x415.png?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-1024x531.png?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-1200x623.png?strip=all 1200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04-1536x797.png?strip=all 1536w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all 1675w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all&amp;w=502 502w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all&amp;w=670 670w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all&amp;w=1340 1340w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_04.png?strip=all&amp;w=450 450w\" sizes=\"(max-width: 846px) 100vw, 846px\" \/><\/p>\n<p>The Tanzanian government is doing what it can. It has defined Amana Hospital as the headquarters for Corona patients, banned gatherings, and closed schools&#8230; but even these hospitals lack basic equipment.<\/p>\n<p>In addition, there is another important problem:<br \/>\nWhen people are sick, the first thing they do is not take a crowded bus to go to another part of the 5 million metropolis. No, they go to the local health center or hospital, such as Rugambwa Hospital. The doctors and nurses care for the patients until they are transferred, which can take up to three days. But in the health centers, there is hardly any protective clothing and no FFP2 protective masks, as the CSSC sees on a daily basis. If this does not change very quickly, then there is a danger that basic health care for the population in<br \/>\nDar es Salaam collapses. It&#8217;s just as critical as in the fire department.<\/p>\n<p><strong>In these areas, partners are asking for money for infection control, protective clothing, disinfectants, and masks.<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;width:66.6666666667%;width:calc(66.6666666667% - ( ( 4% ) * 0.666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-3\"><p>Given the particular situation and urgency, it is important at the moment to help the people of Dar es Salaam early before the disease spreads more widely. Still, the needed things can be bought on the local market.<\/p>\n<p>This emergency aid is needed now and we can ensure that it reaches the population quickly and directly because we have been working with our partners for a long time.<\/p>\n<p>Therefore, we would like to ask you to support us and donate for the health workers and the disadvantaged in Dar es Salaam. Because:<\/p>\n<blockquote>\n<p>&#8220;Solidarity is tenderness between people.&#8221;<\/p>\n<\/blockquote>\n<p><strong>ASANTE SANA FOR YOUR DONATION*!<\/strong><\/p>\n<p>Circle of Friends Hamburg-Dar es Salaam e.V.<br \/>\nIBAN: DE84 8306 5408 0004 8587 19<br \/>\nBIC: GENO DEF1 SLR<br \/>\nKEYWORD:<strong> \u201eCorona Hilfe Dar\u201c<\/strong><\/p>\n<p>* According to the decision of the Federal Ministry of Finance of 09 April 2020, donations to Corona help can be tax-deductible in unlimited amounts, by proof of cash deposit or bank statement (also PC).<\/p>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:30px;--awb-padding-left:20px;--awb-bg-size:cover;--awb-border-color:#e53540;--awb-border-top:4px;--awb-border-right:4px;--awb-border-bottom:4px;--awb-border-left:4px;--awb-border-style:solid;width:33.3333333333%;width:calc(33.3333333333% - ( ( 4% ) * 0.333333333333 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\"><h1 class=\"title-heading-left\" style=\"margin:0;\"><h2>Do you have any further questions?<\/h2><\/h1><\/div><div class=\"fusion-text fusion-text-4\"><p>Inken Bruns<br \/>\nCooperation Center<br \/>\nHamburg \u2013 Dar es Salaam<br \/>\n<a href=\"bruns@diakonie-hamburg.de\">bruns@diakonie-hamburg.de<\/a><\/p>\n<p>Phone 040 30620-429<br \/>\nFax 040 30620-340<\/p>\n<p><strong>Feel free to call me!<\/strong><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-max-width:200px;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/screen_HH-DES_Spendenbrief_aktiv_200515-1.pdf\" target=\"_self\" aria-label=\"web_COVID_AUFRUF2\"><img decoding=\"async\" width=\"718\" height=\"402\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all\" alt class=\"img-responsive wp-image-4864\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2-200x112.png?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2-400x224.png?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2-600x336.png?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all 718w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all&amp;w=71 71w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all&amp;w=143 143w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all&amp;w=287 287w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all&amp;w=502 502w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF2.png?strip=all&amp;w=450 450w\" sizes=\"(max-width: 1024px) 100vw, 400px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:20px;--awb-padding-bottom:30px;--awb-bg-size:cover;--awb-border-color:#00a4c4;--awb-border-top:0;--awb-border-right:0;--awb-border-bottom:0;--awb-border-left:0;--awb-border-style:solid;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1 lightbox-enabled\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel\" data-autoplay=\"yes\" data-columns=\"3\" data-itemmargin=\"30\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"auto\" data-scrollitems=\"1\" style=\"--awb-columns:3;--awb-column-spacing:30px;\"><div class=\"swiper-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"web_verkaeufer_681A4599\" aria-label=\"web_verkaeufer_681A4599\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_verkaeufer_681A4599.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Masken2\" aria-label=\"Masken2\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"719\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2-400x266.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2-600x399.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken2.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Masken im Stadtbild\" aria-label=\"Masken im Stadtbild\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild-400x267.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild-600x400.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Masken-im-Stadtbild.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"web_eisverkaeufer_681A4258\" aria-label=\"web_eisverkaeufer_681A4258\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_eisverkaeufer_681A4258.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Verkauf von Wassereimern\" aria-label=\"Verkauf von Wassereimern\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"719\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern-400x266.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern-600x399.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/06\/Verkauf-von-Wassereimern.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Zitronen und Organgen gegen Corona (alle)\" aria-label=\"Zitronen und Organgen gegen Corona (alle)\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle-400x267.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle-600x400.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Zitronen-und-Organgen-gegen-Corona-alle.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Keine Arbeit\" aria-label=\"Keine Arbeit\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"719\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit-400x266.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit-600x399.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Keine-Arbeit.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Grundausstattung &#8211; Maske an Motorrad\" aria-label=\"Grundausstattung &#8211; Maske an Motorrad\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad-400x267.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad-600x400.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Grundausstattung-Maske-an-Motorrad.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"web_info_681A5911\" aria-label=\"web_info_681A5911\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_info_681A5911.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"Leben mit Corona\" aria-label=\"Leben mit Corona\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"663\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona-200x123.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona-400x246.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona-600x368.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona-800x491.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/Leben-mit-Corona.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"\u00a9 IMANI NSAMILA\" data-title=\"WIe soll das nur weitergehen\" aria-label=\"WIe soll das nur weitergehen\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen-400x267.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen-600x400.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/WIe-soll-das-nur-weitergehen.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"Keine Kunden\n\u00a9 IMANI NSAMILA\" data-title=\"keine Kunden\" aria-label=\"keine Kunden\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden-200x133.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden-400x267.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden-600x400.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden-800x533.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all 1080w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=108 108w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=324 324w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=540 540w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=864 864w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=972 972w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/keine-Kunden.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"web_nahverkauf_681A4871\" aria-label=\"web_nahverkauf_681A4871\" href=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&w=2560\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_nahverkauf_681A4871.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 960px) 370px, (min-width: 800px) 555px, (min-width: 640px) 800px, \" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-text fusion-text-5\"><p>Asante Sana for the use of the great pictures! \u00a9 <a href=\"http:\/\/imaninsamila.com\">IMANI NSAMILA<\/a><\/p>\n<p>He is also happy to receive a donation or collaboration!<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:10%;--awb-padding-bottom:30px;--awb-padding-left:10%;--awb-background-image:url(&quot;https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/03\/verlauf_synergie2.png?strip=all&w=1170&quot;);--awb-background-size:cover;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:20px;--awb-padding-bottom:30px;--awb-bg-size:cover;--awb-border-color:#00a4c4;--awb-border-top:0;--awb-border-right:0;--awb-border-bottom:0;--awb-border-left:0;--awb-border-style:solid;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-6\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Our partners who need concrete help<\/span><\/h1>\n<\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-4 fusion-columns-total-8 fusion-content-boxes-1 content-boxes-icon-on-top content-left\" style=\"--awb-hover-accent-color:#ffffff;--awb-circle-hover-accent-color:transparent;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover content-box-column-first-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/talent-search-and-empowerment\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/04\/AKTUER_TSE_400x400px.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Talent Search and Empowerment<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/paulchen-esperanza\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/AKTEUR_PaulchenE_Logo_400x400.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Paulchen Esperenza Foundation<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-3 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/kcc\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/AKTEUR_KCC_Logo_400x400.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">KCC<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-4 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/ladies-joint-forum\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/AKTEUR_Dar_Logo_Ladies-Forum_400x400_200512.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Ladies Joint Forum<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-5 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover content-box-column-first-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/talent-search-and-empowerment\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/03\/AKTEUR_TanzaniaYouthCoalition_LOGO_400x400_200324.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Tanzania Youth Coalition (TYC)<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-6 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/amana-referal-hospital\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/02\/L_Aktuer_Amana-400x400-1.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Amana Referral Hospital<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-7 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/crh\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/03\/L_Aktuer_Rugambwa_400x400.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Catholic Cardinal Rugambwa Hospital<\/h2><\/a><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-8 col-lg-3 col-md-3 col-sm-3 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-button icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/hamburg-daressalaam.de\/fire-and-rescue-force-tanzania\/\" target=\"_self\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/AKTEUR_FEUERdar_400x400_200320.png?strip=all&resize=230%2C230\" width=\"230\" height=\"230\" alt=\"\" \/><\/div><h2 class=\"content-box-heading\" style=\"--h2_typography-font-size:23px;line-height:28px;\">Fire and Rescue Force Tanzania<\/h2><\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:10%;--awb-padding-bottom:30px;--awb-padding-left:10%;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:20px;--awb-padding-bottom:30px;--awb-bg-size:cover;--awb-border-color:#00a4c4;--awb-border-top:0;--awb-border-right:0;--awb-border-bottom:0;--awb-border-left:0;--awb-border-style:solid;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-7\"><h1 style=\"text-align: center;\">Corona news<\/h1>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:40px;width:100%;max-width:100px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#e53540;border-color:#e53540;border-top-width:4px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-pagination fusion-blog-layout-center\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:15px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -15px !important; margin-right:-15px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-pagination fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-4 isotope fusion-blog-equal-heights\" data-pages=\"2\" data-grid-col-space=\"30\" style=\"margin: -15px -15px 0;min-height:500px;\"><article id=\"blog-1-post-5626\" class=\"fusion-post-grid post-5626 post type-post status-publish format-standard has-post-thumbnail hentry category-articles category-corona-en category-news\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/08\/web_Marangu-Corona-Hilfe-1.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1120px) 270px, (min-width: 960px) 360px, (min-width: 800px) 540px, (min-width: 640px) 800px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/hamburg-daressalaam.de\/en\/corona-relief-action-in-marangu\/\">\n\t\t\t\t\t\tCorona relief action in Marangu\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/hamburg-daressalaam.de\/en\/corona-relief-action-in-marangu\/\" aria-label=\"Corona relief action in Marangu\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/corona-relief-action-in-marangu\/\">Corona relief action in Marangu<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/author\/gaby\/\" title=\"Posts by Gaby\" rel=\"author\">Gaby<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-05-30T22:39:44+02:00<\/span><span>02. August 2020<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-5629\" class=\"fusion-post-grid post-5629 post type-post status-publish format-standard has-post-thumbnail hentry category-articles category-corona-en category-news\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/07\/web_Leonard-malt.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1120px) 270px, (min-width: 960px) 360px, (min-width: 800px) 540px, (min-width: 640px) 800px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/hamburg-daressalaam.de\/en\/sdg-street-art-in-kigamboni\/\">\n\t\t\t\t\t\tSDG Street Art in Kigamboni\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/hamburg-daressalaam.de\/en\/sdg-street-art-in-kigamboni\/\" aria-label=\"SDG Street Art in Kigamboni\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/sdg-street-art-in-kigamboni\/\">SDG Street Art in Kigamboni<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/author\/gaby\/\" title=\"Posts by Gaby\" rel=\"author\">Gaby<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-05-30T22:42:47+02:00<\/span><span>04. July 2020<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-5648\" class=\"fusion-post-grid post-5648 post type-post status-publish format-standard has-post-thumbnail hentry category-corona-en category-news\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_NEWS_TSE-Corona-Handwaschstation-3.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1120px) 270px, (min-width: 960px) 360px, (min-width: 800px) 540px, (min-width: 640px) 800px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/hamburg-daressalaam.de\/en\/the-creative-center-can-continue-to-care-for-children-and-young-people\/\">\n\t\t\t\t\t\tThe creative center can continue to care for children and young people.\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/hamburg-daressalaam.de\/en\/the-creative-center-can-continue-to-care-for-children-and-young-people\/\" aria-label=\"The creative center can continue to care for children and young people.\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/the-creative-center-can-continue-to-care-for-children-and-young-people\/\">The creative center can continue to care for children and young people.<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/author\/gaby\/\" title=\"Posts by Gaby\" rel=\"author\">Gaby<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-06-01T18:06:13+02:00<\/span><span>30. May 2020<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-5672\" class=\"fusion-post-grid post-5672 post type-post status-publish format-standard has-post-thumbnail hentry category-corona-en category-news\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515-200x150.jpg?strip=all 200w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515-400x300.jpg?strip=all 400w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515-600x450.jpg?strip=all 600w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515-800x600.jpg?strip=all 800w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all 1024w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=102 102w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=307 307w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=512 512w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=716 716w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=921 921w, https:\/\/cdn.hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_Rugambwa_200515.jpg?strip=all&amp;w=450 450w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1120px) 270px, (min-width: 960px) 360px, (min-width: 800px) 540px, (min-width: 640px) 800px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/hamburg-daressalaam.de\/en\/rugambwa-hospital-has-been-equipped\/\">\n\t\t\t\t\t\tRugambwa Hospital has been equipped!\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/hamburg-daressalaam.de\/en\/rugambwa-hospital-has-been-equipped\/\" aria-label=\"Rugambwa Hospital has been equipped!\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/rugambwa-hospital-has-been-equipped\/\">Rugambwa Hospital has been equipped!<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/hamburg-daressalaam.de\/en\/author\/gaby\/\" title=\"Posts by Gaby\" rel=\"author\">Gaby<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-06-04T15:12:14+02:00<\/span><span>17. May 2020<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><div class=\"pagination clearfix\"><span class=\"current\">1<\/span><a href=\"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages\/5279\/page\/2\/\" class=\"inactive\">2<\/a><a class=\"pagination-next\" rel=\"next\" href=\"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages\/5279\/page\/2\/\"><span class=\"page-text\">Next<\/span><span class=\"page-next\"><\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-text fusion-text-8\"><h4 style=\"text-align: center;\"><span style=\"color: #00a5c4;\">More news in brief<\/span><\/h4>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-testimonials clean fusion-testimonials-1\" style=\"--awb-textcolor:#e53540;--awb-backgroundcolor:var(--awb-color2);\" data-random=\"0\" data-speed=\"4000\"><div class=\"reviews\"><div class=\"review active-testimonial male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.filme-aus-afrika.de\/DE\/das-projekt\/online-film-angebot\/?fbclid=IwAR2-zcDjCK4s87LUdd_DtVxiT2kyhaNcW8IIBwuGZEFmc2VmjlVwvSRa2ok\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #333333;\">MOVIES FROM AFRICA &#8211; ONLINE OFFERS<br \/>\nFilminitiativ K\u00f6ln e.V. provides us with films from Africa in full length.<br \/>\nThank you! We wish you stimulating movie nights.<\/span><\/a><\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p style=\"text-align: center;\">Video from Tanzania<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/hashtag\/tanzaniaunforgettable?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARCs94Sk8gVZE_Kz9ZgjfKOrqEjVyG4VeSxVPpPfYFlkRFcq2x8AO-cTDELCOZIIEhhbWmoi3Rhj-v35rNUvxKFlPBX6uL6XbPj7g4J01Ryvmpj4i5iuiQriVYInW_RGnqt6VdKfN43EdLmQq761Wz3hpx-FLvswmEPRigQmgh0_ByJ-BN6D_iqugz83OTo_xeanvEp3zYkPn0lTIRsAIlCPJtxw6q6HaTWE867BygY1aorpmbaNRKTHXP1bfg2LRbpRzJnXTyUBXQznXhxJ3XA1rT1YzD1vkzA1hfgFNjbafDY8ZYlf5w5CCdSFKaSp0EgWMqzUYZOCV6FwSzR6ZdQMIgYJTye4&amp;__tn__=%2ANK-R\"><span style=\"color: #333333;\">#TanzaniaUnforgettable<\/span><\/a><\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">Video from Tanzania<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\"><a href=\"https:\/\/www.facebook.com\/hashtag\/savetourism?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARCs94Sk8gVZE_Kz9ZgjfKOrqEjVyG4VeSxVPpPfYFlkRFcq2x8AO-cTDELCOZIIEhhbWmoi3Rhj-v35rNUvxKFlPBX6uL6XbPj7g4J01Ryvmpj4i5iuiQriVYInW_RGnqt6VdKfN43EdLmQq761Wz3hpx-FLvswmEPRigQmgh0_ByJ-BN6D_iqugz83OTo_xeanvEp3zYkPn0lTIRsAIlCPJtxw6q6HaTWE867BygY1aorpmbaNRKTHXP1bfg2LRbpRzJnXTyUBXQznXhxJ3XA1rT1YzD1vkzA1hfgFNjbafDY8ZYlf5w5CCdSFKaSp0EgWMqzUYZOCV6FwSzR6ZdQMIgYJTye4&amp;__tn__=%2ANK-R\">#SaveTourism<\/a><\/span><\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">Video from Tanzania<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\"><a href=\"https:\/\/www.facebook.com\/hashtag\/traveltomorrow?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARCs94Sk8gVZE_Kz9ZgjfKOrqEjVyG4VeSxVPpPfYFlkRFcq2x8AO-cTDELCOZIIEhhbWmoi3Rhj-v35rNUvxKFlPBX6uL6XbPj7g4J01Ryvmpj4i5iuiQriVYInW_RGnqt6VdKfN43EdLmQq761Wz3hpx-FLvswmEPRigQmgh0_ByJ-BN6D_iqugz83OTo_xeanvEp3zYkPn0lTIRsAIlCPJtxw6q6HaTWE867BygY1aorpmbaNRKTHXP1bfg2LRbpRzJnXTyUBXQznXhxJ3XA1rT1YzD1vkzA1hfgFNjbafDY8ZYlf5w5CCdSFKaSp0EgWMqzUYZOCV6FwSzR6ZdQMIgYJTye4&amp;__tn__=%2ANK-R\">#TravelTomorrow<\/a><\/span><\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">Video from Tanzania<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\"><a href=\"https:\/\/twitter.com\/TTBTanzania\/status\/1245696379403620352\">on Twitter<\/a><\/span><\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p>The St.Pauli Girlz arrived safely from Dar es Salaam on Sunday.<\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p>The German-Tanzanian Partnership had to recall 30 volunteers from Tanzania.<\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><div class=\"review male\"><div class=\"testimonial-thumbnail doe\"><\/div><blockquote class=\"testimonials-shortcode-blockquote\"><q class=\"fusion-clearfix\">\n<p>A Hamburg city planner continues to be in our twin city.<\/p>\n<\/q><\/blockquote><div class=\"author\"><span class=\"company-name\"><\/span><\/div><\/div><\/div><div class=\"testimonial-pagination\" id=\"fusion-testimonials-1\"><a href=\"#\" aria-label=\"Testimonial Pagination\"  class=\"activeSlide\"><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><a href=\"#\" aria-label=\"Testimonial Pagination\" ><\/a><\/div><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:13px;--awb-content-font-size:16px;--awb-icon-alignment:left;--awb-hover-color:#f9f9f9;--awb-border-color:#cccccc;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#ffffff;--awb-title-color:#e53540;--awb-content-color:#000000;--awb-icon-box-color:#e53540;--awb-toggle-hover-accent-color:#00a4c4;--awb-title-font-family:&quot;Lexend Exa&quot;;--awb-title-font-weight:regular;--awb-title-font-style:normal;--awb-title-font-size:16px;--awb-title-letter-spacing:0px;--awb-title-line-height:1.5;--awb-content-font-family:&quot;Montserrat&quot;;--awb-content-font-style:normal;--awb-content-font-weight:regular;\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-5672-2\"><div class=\"fusion-panel panel-default panel-62ea90af6908936a6 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_62ea90af6908936a6\"><a aria-expanded=\"false\" aria-controls=\"62ea90af6908936a6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5672-2\" data-target=\"#62ea90af6908936a6\" href=\"#62ea90af6908936a6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Informations about Corona in English <\/span><\/a><\/h4><\/div><div id=\"62ea90af6908936a6\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_62ea90af6908936a6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>for our friends from Tanzania in Hamburg and elsewhere<\/p>\n<p>Dear Friends, we put together some links for you to find current information about Corona in English.<\/p>\n<p>Current news about the situation and regulations in Hamburg from the City:<br \/>\n<u><a href=\"http:\/\/www.hamburg.com\">www.hamburg.com<\/a><\/u><\/p>\n<p>Information about the laborlaws under Corona:<br \/>\n<u><a href=\"http:\/\/www.bmas.de\">www.bmas.de<\/a><\/u><\/p>\n<p>If you are self-employed there will be funds to take care of you, that you can apply for, from the end of March &#8211; Please turn to someone from the Partnership who can help you with that.<\/p>\n<p>And a good worldwide site about the numbers regarding Corona.<br \/>\nEspecially interesting: it is very much up to date and you can sort the countries according to each topic<br \/>\n<u><a href=\"https:\/\/www.worldometers.info\/coronavirus\/\">https:\/\/www.worldometers.info\/coronavirus\/<\/a><\/u><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9715c72731e9ad57c fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_9715c72731e9ad57c\"><a aria-expanded=\"false\" aria-controls=\"9715c72731e9ad57c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5672-2\" data-target=\"#9715c72731e9ad57c\" href=\"#9715c72731e9ad57c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Artists in Germany and Tanzania become creative: songs of encouragement <\/span><\/a><\/h4><\/div><div id=\"9715c72731e9ad57c\" class=\"panel-collapse collapse \" araia-labelledby=\"toggle_9715c72731e9ad57c\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong>North Germany <\/strong><\/p>\n<p>Corona oh na na<br \/>\nA North German banter song for good humor and encouragement<br \/>\n<a href=\"https:\/\/youtu.be\/r3QeMKBVAP0\" target=\"_blank\" rel=\"noopener noreferrer\">To the song<\/a><\/p>\n<p>Sebel &#8211; Stand together<br \/>\n<a href=\"https:\/\/youtu.be\/tOG6gzkNZV4\" target=\"_blank\" rel=\"noopener noreferrer\">About the song (Thanks Martina Shimkat)<\/a><\/p>\n<p><strong>Dar es Salaam <\/strong><\/p>\n<p>Corona<br \/>\nRavanny, one of the most famous music stars in Tanzania made this music video.<br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=mzzYz0DMPDU\" target=\"_blank\" rel=\"noopener noreferrer\">To the song<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-5279","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/\" \/>\n<meta property=\"og:site_name\" content=\"Freundeskreis Hamburg-Dar es Salaam\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T20:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/\",\"url\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/\",\"name\":\"COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/web_COVID_AUFRUF4.png\",\"datePublished\":\"2020-05-15T12:31:59+00:00\",\"dateModified\":\"2022-05-09T20:11:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/web_COVID_AUFRUF4.png\",\"contentUrl\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/web_COVID_AUFRUF4.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/covid-19-in-tanzania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 in Tanzania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/\",\"name\":\"Freundeskreis Hamburg-Dar es Salaam\",\"description\":\"Freundeskreis der St\u00e4dtepartnerschaft Hamburg-Dar es Salaam\",\"publisher\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#organization\",\"name\":\"Freundeskreis Dar es Salaam \u2013 Hamburg e.V.\",\"url\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Logo-400s.png\",\"contentUrl\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Logo-400s.png\",\"width\":400,\"height\":160,\"caption\":\"Freundeskreis Dar es Salaam \u2013 Hamburg e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/hamburg-daressalaam.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/","og_locale":"en_US","og_type":"article","og_title":"COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam","og_url":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/","og_site_name":"Freundeskreis Hamburg-Dar es Salaam","article_modified_time":"2022-05-09T20:11:39+00:00","og_image":[{"url":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/","url":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/","name":"COVID-19 in Tanzania - Freundeskreis Hamburg-Dar es Salaam","isPartOf":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/#primaryimage"},"image":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/#primaryimage"},"thumbnailUrl":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png","datePublished":"2020-05-15T12:31:59+00:00","dateModified":"2022-05-09T20:11:39+00:00","breadcrumb":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/#primaryimage","url":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png","contentUrl":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/05\/web_COVID_AUFRUF4.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hamburg-daressalaam.de\/en\/covid-19-in-tanzania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hamburg-daressalaam.de\/en\/home\/"},{"@type":"ListItem","position":2,"name":"COVID-19 in Tanzania"}]},{"@type":"WebSite","@id":"https:\/\/hamburg-daressalaam.de\/en\/#website","url":"https:\/\/hamburg-daressalaam.de\/en\/","name":"Freundeskreis Hamburg-Dar es Salaam","description":"Freundeskreis der St\u00e4dtepartnerschaft Hamburg-Dar es Salaam","publisher":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hamburg-daressalaam.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hamburg-daressalaam.de\/en\/#organization","name":"Freundeskreis Dar es Salaam \u2013 Hamburg e.V.","url":"https:\/\/hamburg-daressalaam.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hamburg-daressalaam.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/02\/Logo-400s.png","contentUrl":"https:\/\/hamburg-daressalaam.de\/wp-content\/uploads\/2020\/02\/Logo-400s.png","width":400,"height":160,"caption":"Freundeskreis Dar es Salaam \u2013 Hamburg e.V."},"image":{"@id":"https:\/\/hamburg-daressalaam.de\/en\/#\/schema\/logo\/image\/"}}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages\/5279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/comments?post=5279"}],"version-history":[{"count":11,"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages\/5279\/revisions"}],"predecessor-version":[{"id":5290,"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/pages\/5279\/revisions\/5290"}],"wp:attachment":[{"href":"https:\/\/hamburg-daressalaam.de\/en\/wp-json\/wp\/v2\/media?parent=5279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}